{"id":23,"date":"2018-02-10T00:16:22","date_gmt":"2018-02-10T06:16:22","guid":{"rendered":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n.jpg"},"modified":"2018-02-10T00:16:22","modified_gmt":"2018-02-10T06:16:22","slug":"27654449_2125082187727743_5845974331085335118_n","status":"inherit","type":"attachment","link":"https:\/\/pages.stolaf.edu\/esanzoles2018\/2018\/02\/07\/watch-this-space\/27654449_2125082187727743_5845974331085335118_n\/","title":{"rendered":"27654449_2125082187727743_5845974331085335118_n"},"author":2720,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-23","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n-300x169.jpg 300w, https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n-150x84.jpg 150w, https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n-768x432.jpg 768w, https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":540,"file":"2018\/02\/27654449_2125082187727743_5845974331085335118_n.jpg","sizes":{"thumbnail":{"file":"27654449_2125082187727743_5845974331085335118_n-150x84.jpg","width":150,"height":84,"mime_type":"image\/jpeg","source_url":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n-150x84.jpg"},"medium":{"file":"27654449_2125082187727743_5845974331085335118_n-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n-300x169.jpg"},"medium_large":{"file":"27654449_2125082187727743_5845974331085335118_n-768x432.jpg","width":768,"height":432,"mime_type":"image\/jpeg","source_url":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n-768x432.jpg"},"post-thumbnail":{"file":"27654449_2125082187727743_5845974331085335118_n-825x510.jpg","width":825,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n-825x510.jpg"},"full":{"file":"27654449_2125082187727743_5845974331085335118_n.jpg","width":960,"height":540,"mime_type":"image\/jpeg","source_url":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":9,"source_url":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-content\/uploads\/sites\/1026\/2018\/02\/27654449_2125082187727743_5845974331085335118_n.jpg","_links":{"self":[{"href":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-json\/wp\/v2\/media\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-json\/wp\/v2\/users\/2720"}],"replies":[{"embeddable":true,"href":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-json\/wp\/v2\/comments?post=23"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":9,"href":"https:\/\/pages.stolaf.edu\/esanzoles2018\/wp-json\/wp\/v2\/posts\/9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}